{"id":680,"date":"2018-04-20T12:11:35","date_gmt":"2018-04-20T10:11:35","guid":{"rendered":"http:\/\/test.jebensmensching.com\/?p=680"},"modified":"2019-06-25T15:02:44","modified_gmt":"2019-06-25T13:02:44","slug":"news-deka-immobilien-gmbh-verkauf-bueroensembles-duo-duesseldorf","status":"publish","type":"post","link":"https:\/\/jebensmensching.com\/en\/2018\/04\/20\/news-deka-immobilien-gmbh-verkauf-bueroensembles-duo-duesseldorf\/","title":{"rendered":"Jebens Mensching advises Deka Immobilien GmbH on the sale of the office ensemble DUO in D\u00fcsseldorf"},"content":{"rendered":"<p>Deka Immobilien GmbH has sold the office ensemble DUO in D\u00fcsseldorf to holding companies of the Harbert European Real Estate Fund (HEREF IV LP (UK)). The property was part of the open-ended mutual property funds Deka-Immoblien Europa. The parties agreed to keep the purchase price confidential.<\/p>\n<p>The DUO consists of an arc-shaped low rise building and an 18-storey high rise with a total of about 34,000 sqm lettable space and 431 parking spaces. Both premises were built in 1993, the low rise was revitalized in 2012\/13 and as a result was awarded with certificate in Leadership in Energy and Environmental Design in Gold (LEED). The property is situated in the Grafenberg submarket, in the eastern part of the city. It is currently let to three tenants.<\/p>\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Die Deka Immobilien GmbH hat das B\u00fcroensemble \u201eDUO\u201c in D\u00fcsseldorf ver\u00e4u\u00dfert. Der Komplex wurde durch Beteiligungsgesellschaften des Harbert European Real Estate Fund \u201eHEREF IV LP (UK)\u201c erworben. Die Liegenschaft stammt aus dem Portfolio des Offenen Immobilien-Publikumsfonds Deka-Immobilien Europa. \u00dcber den Verkaufspreis wurde Stillschweigen vereinbart. Das \u201eDUO\u201c besteht aus einem bogenf\u00f6rmigen Flachbau, einem Hochhaus mit 18 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":960,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-680","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"JM\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/jebensmensching.com\/en\/2018\/04\/20\/news-deka-immobilien-gmbh-verkauf-bueroensembles-duo-duesseldorf\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_GB\" \/>\n\t\t<meta property=\"og:site_name\" content=\"JEBENS MENSCHING | Rechtsanw\u00e4lte, Steuerberater\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Jebens Mensching ber\u00e4t die Deka Immobilien GmbH beim Verkauf des B\u00fcroensembles \u201eDUO\u201c in D\u00fcsseldorf | JEBENS MENSCHING\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/jebensmensching.com\/en\/2018\/04\/20\/news-deka-immobilien-gmbh-verkauf-bueroensembles-duo-duesseldorf\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-04-20T10:11:35+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-06-25T13:02:44+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Jebens Mensching ber\u00e4t die Deka Immobilien GmbH beim Verkauf des B\u00fcroensembles \u201eDUO\u201c in D\u00fcsseldorf | JEBENS MENSCHING\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jebensmensching.com\\\/en\\\/2018\\\/04\\\/20\\\/news-deka-immobilien-gmbh-verkauf-bueroensembles-duo-duesseldorf\\\/#article\",\"name\":\"Jebens Mensching ber\\u00e4t die Deka Immobilien GmbH beim Verkauf des B\\u00fcroensembles \\u201eDUO\\u201c in D\\u00fcsseldorf | JEBENS MENSCHING\",\"headline\":\"Jebens Mensching ber\\u00e4t die Deka Immobilien GmbH beim Verkauf des B\\u00fcroensembles \\u201eDUO\\u201c in D\\u00fcsseldorf\",\"author\":{\"@id\":\"https:\\\/\\\/jebensmensching.com\\\/en\\\/author\\\/caro\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/jebensmensching.com\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/jebensmensching.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/JM-Header_News-Full.jpg\",\"width\":1973,\"height\":1440},\"datePublished\":\"2018-04-20T12:11:35+02:00\",\"dateModified\":\"2019-06-25T15:02:44+02:00\",\"inLanguage\":\"en-GB\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jebensmensching.com\\\/en\\\/2018\\\/04\\\/20\\\/news-deka-immobilien-gmbh-verkauf-bueroensembles-duo-duesseldorf\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/jebensmensching.com\\\/en\\\/2018\\\/04\\\/20\\\/news-deka-immobilien-gmbh-verkauf-bueroensembles-duo-duesseldorf\\\/#webpage\"},\"articleSection\":\"News\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jebensmensching.com\\\/en\\\/2018\\\/04\\\/20\\\/news-deka-immobilien-gmbh-verkauf-bueroensembles-duo-duesseldorf\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/jebensmensching.com\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/jebensmensching.com\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/jebensmensching.com\\\/en\\\/category\\\/news\\\/#listItem\",\"name\":\"News\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/jebensmensching.com\\\/en\\\/category\\\/news\\\/#listItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/jebensmensching.com\\\/en\\\/category\\\/news\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/jebensmensching.com\\\/en\\\/2018\\\/04\\\/20\\\/news-deka-immobilien-gmbh-verkauf-bueroensembles-duo-duesseldorf\\\/#listItem\",\"name\":\"Jebens Mensching ber\\u00e4t die Deka Immobilien GmbH beim Verkauf des B\\u00fcroensembles \\u201eDUO\\u201c in D\\u00fcsseldorf\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/jebensmensching.com\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/jebensmensching.com\\\/en\\\/2018\\\/04\\\/20\\\/news-deka-immobilien-gmbh-verkauf-bueroensembles-duo-duesseldorf\\\/#listItem\",\"position\":3,\"name\":\"Jebens Mensching ber\\u00e4t die Deka Immobilien GmbH beim Verkauf des B\\u00fcroensembles \\u201eDUO\\u201c in D\\u00fcsseldorf\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/jebensmensching.com\\\/en\\\/category\\\/news\\\/#listItem\",\"name\":\"News\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jebensmensching.com\\\/en\\\/#organization\",\"name\":\"JEBENS MENSCHING\",\"description\":\"Rechtsanw\\u00e4lte, Steuerberater\",\"url\":\"https:\\\/\\\/jebensmensching.com\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jebensmensching.com\\\/en\\\/author\\\/caro\\\/#author\",\"url\":\"https:\\\/\\\/jebensmensching.com\\\/en\\\/author\\\/caro\\\/\",\"name\":\"JM\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/jebensmensching.com\\\/en\\\/2018\\\/04\\\/20\\\/news-deka-immobilien-gmbh-verkauf-bueroensembles-duo-duesseldorf\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/487fbd8f46ead2f723e2edf00f6ad6dc9d9584a800475b81275377b607bce69f?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"JM\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jebensmensching.com\\\/en\\\/2018\\\/04\\\/20\\\/news-deka-immobilien-gmbh-verkauf-bueroensembles-duo-duesseldorf\\\/#webpage\",\"url\":\"https:\\\/\\\/jebensmensching.com\\\/en\\\/2018\\\/04\\\/20\\\/news-deka-immobilien-gmbh-verkauf-bueroensembles-duo-duesseldorf\\\/\",\"name\":\"Jebens Mensching ber\\u00e4t die Deka Immobilien GmbH beim Verkauf des B\\u00fcroensembles \\u201eDUO\\u201c in D\\u00fcsseldorf | JEBENS MENSCHING\",\"inLanguage\":\"en-GB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jebensmensching.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jebensmensching.com\\\/en\\\/2018\\\/04\\\/20\\\/news-deka-immobilien-gmbh-verkauf-bueroensembles-duo-duesseldorf\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/jebensmensching.com\\\/en\\\/author\\\/caro\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/jebensmensching.com\\\/en\\\/author\\\/caro\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/jebensmensching.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/JM-Header_News-Full.jpg\",\"@id\":\"https:\\\/\\\/jebensmensching.com\\\/en\\\/2018\\\/04\\\/20\\\/news-deka-immobilien-gmbh-verkauf-bueroensembles-duo-duesseldorf\\\/#mainImage\",\"width\":1973,\"height\":1440},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jebensmensching.com\\\/en\\\/2018\\\/04\\\/20\\\/news-deka-immobilien-gmbh-verkauf-bueroensembles-duo-duesseldorf\\\/#mainImage\"},\"datePublished\":\"2018-04-20T12:11:35+02:00\",\"dateModified\":\"2019-06-25T15:02:44+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jebensmensching.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/jebensmensching.com\\\/en\\\/\",\"name\":\"JEBENS MENSCHING\",\"description\":\"Rechtsanw\\u00e4lte, Steuerberater\",\"inLanguage\":\"en-GB\",\"publisher\":{\"@id\":\"https:\\\/\\\/jebensmensching.com\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Jebens Mensching ber\u00e4t die Deka Immobilien GmbH beim Verkauf des B\u00fcroensembles \u201eDUO\u201c in D\u00fcsseldorf | JEBENS MENSCHING","description":"","canonical_url":"https:\/\/jebensmensching.com\/en\/2018\/04\/20\/news-deka-immobilien-gmbh-verkauf-bueroensembles-duo-duesseldorf\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jebensmensching.com\/en\/2018\/04\/20\/news-deka-immobilien-gmbh-verkauf-bueroensembles-duo-duesseldorf\/#article","name":"Jebens Mensching ber\u00e4t die Deka Immobilien GmbH beim Verkauf des B\u00fcroensembles \u201eDUO\u201c in D\u00fcsseldorf | JEBENS MENSCHING","headline":"Jebens Mensching ber\u00e4t die Deka Immobilien GmbH beim Verkauf des B\u00fcroensembles \u201eDUO\u201c in D\u00fcsseldorf","author":{"@id":"https:\/\/jebensmensching.com\/en\/author\/caro\/#author"},"publisher":{"@id":"https:\/\/jebensmensching.com\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/jebensmensching.com\/wp-content\/uploads\/2019\/04\/JM-Header_News-Full.jpg","width":1973,"height":1440},"datePublished":"2018-04-20T12:11:35+02:00","dateModified":"2019-06-25T15:02:44+02:00","inLanguage":"en-GB","mainEntityOfPage":{"@id":"https:\/\/jebensmensching.com\/en\/2018\/04\/20\/news-deka-immobilien-gmbh-verkauf-bueroensembles-duo-duesseldorf\/#webpage"},"isPartOf":{"@id":"https:\/\/jebensmensching.com\/en\/2018\/04\/20\/news-deka-immobilien-gmbh-verkauf-bueroensembles-duo-duesseldorf\/#webpage"},"articleSection":"News"},{"@type":"BreadcrumbList","@id":"https:\/\/jebensmensching.com\/en\/2018\/04\/20\/news-deka-immobilien-gmbh-verkauf-bueroensembles-duo-duesseldorf\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/jebensmensching.com\/en#listItem","position":1,"name":"Home","item":"https:\/\/jebensmensching.com\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/jebensmensching.com\/en\/category\/news\/#listItem","name":"News"}},{"@type":"ListItem","@id":"https:\/\/jebensmensching.com\/en\/category\/news\/#listItem","position":2,"name":"News","item":"https:\/\/jebensmensching.com\/en\/category\/news\/","nextItem":{"@type":"ListItem","@id":"https:\/\/jebensmensching.com\/en\/2018\/04\/20\/news-deka-immobilien-gmbh-verkauf-bueroensembles-duo-duesseldorf\/#listItem","name":"Jebens Mensching ber\u00e4t die Deka Immobilien GmbH beim Verkauf des B\u00fcroensembles \u201eDUO\u201c in D\u00fcsseldorf"},"previousItem":{"@type":"ListItem","@id":"https:\/\/jebensmensching.com\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/jebensmensching.com\/en\/2018\/04\/20\/news-deka-immobilien-gmbh-verkauf-bueroensembles-duo-duesseldorf\/#listItem","position":3,"name":"Jebens Mensching ber\u00e4t die Deka Immobilien GmbH beim Verkauf des B\u00fcroensembles \u201eDUO\u201c in D\u00fcsseldorf","previousItem":{"@type":"ListItem","@id":"https:\/\/jebensmensching.com\/en\/category\/news\/#listItem","name":"News"}}]},{"@type":"Organization","@id":"https:\/\/jebensmensching.com\/en\/#organization","name":"JEBENS MENSCHING","description":"Rechtsanw\u00e4lte, Steuerberater","url":"https:\/\/jebensmensching.com\/en\/"},{"@type":"Person","@id":"https:\/\/jebensmensching.com\/en\/author\/caro\/#author","url":"https:\/\/jebensmensching.com\/en\/author\/caro\/","name":"JM","image":{"@type":"ImageObject","@id":"https:\/\/jebensmensching.com\/en\/2018\/04\/20\/news-deka-immobilien-gmbh-verkauf-bueroensembles-duo-duesseldorf\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/487fbd8f46ead2f723e2edf00f6ad6dc9d9584a800475b81275377b607bce69f?s=96&d=mm&r=g","width":96,"height":96,"caption":"JM"}},{"@type":"WebPage","@id":"https:\/\/jebensmensching.com\/en\/2018\/04\/20\/news-deka-immobilien-gmbh-verkauf-bueroensembles-duo-duesseldorf\/#webpage","url":"https:\/\/jebensmensching.com\/en\/2018\/04\/20\/news-deka-immobilien-gmbh-verkauf-bueroensembles-duo-duesseldorf\/","name":"Jebens Mensching ber\u00e4t die Deka Immobilien GmbH beim Verkauf des B\u00fcroensembles \u201eDUO\u201c in D\u00fcsseldorf | JEBENS MENSCHING","inLanguage":"en-GB","isPartOf":{"@id":"https:\/\/jebensmensching.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/jebensmensching.com\/en\/2018\/04\/20\/news-deka-immobilien-gmbh-verkauf-bueroensembles-duo-duesseldorf\/#breadcrumblist"},"author":{"@id":"https:\/\/jebensmensching.com\/en\/author\/caro\/#author"},"creator":{"@id":"https:\/\/jebensmensching.com\/en\/author\/caro\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/jebensmensching.com\/wp-content\/uploads\/2019\/04\/JM-Header_News-Full.jpg","@id":"https:\/\/jebensmensching.com\/en\/2018\/04\/20\/news-deka-immobilien-gmbh-verkauf-bueroensembles-duo-duesseldorf\/#mainImage","width":1973,"height":1440},"primaryImageOfPage":{"@id":"https:\/\/jebensmensching.com\/en\/2018\/04\/20\/news-deka-immobilien-gmbh-verkauf-bueroensembles-duo-duesseldorf\/#mainImage"},"datePublished":"2018-04-20T12:11:35+02:00","dateModified":"2019-06-25T15:02:44+02:00"},{"@type":"WebSite","@id":"https:\/\/jebensmensching.com\/en\/#website","url":"https:\/\/jebensmensching.com\/en\/","name":"JEBENS MENSCHING","description":"Rechtsanw\u00e4lte, Steuerberater","inLanguage":"en-GB","publisher":{"@id":"https:\/\/jebensmensching.com\/en\/#organization"}}]},"og:locale":"en_GB","og:site_name":"JEBENS MENSCHING | Rechtsanw\u00e4lte, Steuerberater","og:type":"article","og:title":"Jebens Mensching ber\u00e4t die Deka Immobilien GmbH beim Verkauf des B\u00fcroensembles \u201eDUO\u201c in D\u00fcsseldorf | JEBENS MENSCHING","og:url":"https:\/\/jebensmensching.com\/en\/2018\/04\/20\/news-deka-immobilien-gmbh-verkauf-bueroensembles-duo-duesseldorf\/","article:published_time":"2018-04-20T10:11:35+00:00","article:modified_time":"2019-06-25T13:02:44+00:00","twitter:card":"summary","twitter:title":"Jebens Mensching ber\u00e4t die Deka Immobilien GmbH beim Verkauf des B\u00fcroensembles \u201eDUO\u201c in D\u00fcsseldorf | JEBENS MENSCHING"},"aioseo_meta_data":{"post_id":"680","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-01-13 14:30:46","updated":"2025-06-03 18:39:33","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/jebensmensching.com\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/jebensmensching.com\/en\/category\/news\/\" title=\"News\">News<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tJebens Mensching ber\u00e4t die Deka Immobilien GmbH beim Verkauf des B\u00fcroensembles \u201eDUO\u201c in D\u00fcsseldorf\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/jebensmensching.com\/en"},{"label":"News","link":"https:\/\/jebensmensching.com\/en\/category\/news\/"},{"label":"Jebens Mensching ber\u00e4t die Deka Immobilien GmbH beim Verkauf des B\u00fcroensembles \u201eDUO\u201c in D\u00fcsseldorf","link":"https:\/\/jebensmensching.com\/en\/2018\/04\/20\/news-deka-immobilien-gmbh-verkauf-bueroensembles-duo-duesseldorf\/"}],"_links":{"self":[{"href":"https:\/\/jebensmensching.com\/en\/wp-json\/wp\/v2\/posts\/680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jebensmensching.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jebensmensching.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jebensmensching.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jebensmensching.com\/en\/wp-json\/wp\/v2\/comments?post=680"}],"version-history":[{"count":8,"href":"https:\/\/jebensmensching.com\/en\/wp-json\/wp\/v2\/posts\/680\/revisions"}],"predecessor-version":[{"id":1418,"href":"https:\/\/jebensmensching.com\/en\/wp-json\/wp\/v2\/posts\/680\/revisions\/1418"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jebensmensching.com\/en\/wp-json\/wp\/v2\/media\/960"}],"wp:attachment":[{"href":"https:\/\/jebensmensching.com\/en\/wp-json\/wp\/v2\/media?parent=680"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jebensmensching.com\/en\/wp-json\/wp\/v2\/categories?post=680"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jebensmensching.com\/en\/wp-json\/wp\/v2\/tags?post=680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}